{"id":309,"count":2,"description":"","link":"https:\/\/lacabanasse.fr\/es\/category\/non-classe-fr\/","name":"No clasificado","slug":"non-classe-fr","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des Non class\u00e9 - Mairie La Cabanasse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lacabanasse.fr\/es\/category\/non-classe-fr\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Non class\u00e9 - Mairie La Cabanasse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lacabanasse.fr\/es\/category\/non-classe-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Mairie La Cabanasse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lacabanasse.fr\/category\/non-classe-fr\/\",\"url\":\"https:\/\/lacabanasse.fr\/category\/non-classe-fr\/\",\"name\":\"Archives des Non class\u00e9 - Mairie La Cabanasse\",\"isPartOf\":{\"@id\":\"https:\/\/lacabanasse.fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lacabanasse.fr\/category\/non-classe-fr\/#breadcrumb\"},\"inLanguage\":\"es-ES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lacabanasse.fr\/category\/non-classe-fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/lacabanasse.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non class\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lacabanasse.fr\/#website\",\"url\":\"https:\/\/lacabanasse.fr\/\",\"name\":\"Mairie de la Cabanasse\",\"description\":\"Site officiel  de la Mairie de La Cabanasse dans les Pyr\u00e9n\u00e9es Orientales\",\"publisher\":{\"@id\":\"https:\/\/lacabanasse.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lacabanasse.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lacabanasse.fr\/#organization\",\"name\":\"Mairie de la Cabanasse\",\"url\":\"https:\/\/lacabanasse.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/lacabanasse.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lacabanasse.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-la-cabanasse.jpg\",\"contentUrl\":\"https:\/\/lacabanasse.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-la-cabanasse.jpg\",\"width\":512,\"height\":512,\"caption\":\"Mairie de la Cabanasse\"},\"image\":{\"@id\":\"https:\/\/lacabanasse.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lacabanasse66210\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Non class\u00e9 - Mairie La Cabanasse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lacabanasse.fr\/es\/category\/non-classe-fr\/","og_locale":"es_ES","og_type":"article","og_title":"Archives des Non class\u00e9 - Mairie La Cabanasse","og_url":"https:\/\/lacabanasse.fr\/es\/category\/non-classe-fr\/","og_site_name":"Mairie La Cabanasse","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lacabanasse.fr\/category\/non-classe-fr\/","url":"https:\/\/lacabanasse.fr\/category\/non-classe-fr\/","name":"Archivos sin clasificar - Ayuntamiento de La Cabanasse","isPartOf":{"@id":"https:\/\/lacabanasse.fr\/#website"},"breadcrumb":{"@id":"https:\/\/lacabanasse.fr\/category\/non-classe-fr\/#breadcrumb"},"inLanguage":"es-ES"},{"@type":"BreadcrumbList","@id":"https:\/\/lacabanasse.fr\/category\/non-classe-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lacabanasse.fr\/"},{"@type":"ListItem","position":2,"name":"Non class\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/lacabanasse.fr\/#website","url":"https:\/\/lacabanasse.fr\/","name":"Ayuntamiento de Cabanasse","description":"Sitio web oficial del Ayuntamiento de La Cabanasse en los Pirineos Orientales","publisher":{"@id":"https:\/\/lacabanasse.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lacabanasse.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/lacabanasse.fr\/#organization","name":"Ayuntamiento de Cabanasse","url":"https:\/\/lacabanasse.fr\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/lacabanasse.fr\/#\/schema\/logo\/image\/","url":"https:\/\/lacabanasse.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-la-cabanasse.jpg","contentUrl":"https:\/\/lacabanasse.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-la-cabanasse.jpg","width":512,"height":512,"caption":"Mairie de la Cabanasse"},"image":{"@id":"https:\/\/lacabanasse.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lacabanasse66210\/"]}]}},"_links":{"self":[{"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/categories\/309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/posts?categories=309"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}