{"id":5019,"date":"2025-03-21T09:33:50","date_gmt":"2025-03-21T08:33:50","guid":{"rendered":"https:\/\/lacabanasse.fr\/?post_type=lsvr_document&#038;p=5019"},"modified":"2025-03-21T09:33:51","modified_gmt":"2025-03-21T08:33:51","slug":"dp-0660272500006","status":"publish","type":"lsvr_document","link":"https:\/\/lacabanasse.fr\/es\/documents\/dp-0660272500006\/","title":{"rendered":"DP 0660272500006"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"template":"","meta":{"_eb_attr":"","_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"lsvr_document_cat":[356],"lsvr_document_tag":[],"class_list":["post-5019","lsvr_document","type-lsvr_document","status-publish","hentry","lsvr_document_cat-arretes-dp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DP 0660272500006 - Mairie La Cabanasse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lacabanasse.fr\/es\/documents\/dp-0660272500006\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DP 0660272500006 - Mairie La Cabanasse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lacabanasse.fr\/es\/documents\/dp-0660272500006\/\" \/>\n<meta property=\"og:site_name\" content=\"Mairie La Cabanasse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lacabanasse66210\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T08:33:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/\",\"url\":\"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/\",\"name\":\"DP 0660272500006 - Mairie La Cabanasse\",\"isPartOf\":{\"@id\":\"https:\/\/lacabanasse.fr\/#website\"},\"datePublished\":\"2025-03-21T08:33:50+00:00\",\"dateModified\":\"2025-03-21T08:33:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/lacabanasse.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documents\",\"item\":\"https:\/\/lacabanasse.fr\/es\/documents\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DP 0660272500006\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lacabanasse.fr\/#website\",\"url\":\"https:\/\/lacabanasse.fr\/\",\"name\":\"Mairie de la Cabanasse\",\"description\":\"Site officiel  de la Mairie de La Cabanasse dans les Pyr\u00e9n\u00e9es Orientales\",\"publisher\":{\"@id\":\"https:\/\/lacabanasse.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lacabanasse.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lacabanasse.fr\/#organization\",\"name\":\"Mairie de la Cabanasse\",\"url\":\"https:\/\/lacabanasse.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/lacabanasse.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lacabanasse.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-la-cabanasse.jpg\",\"contentUrl\":\"https:\/\/lacabanasse.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-la-cabanasse.jpg\",\"width\":512,\"height\":512,\"caption\":\"Mairie de la Cabanasse\"},\"image\":{\"@id\":\"https:\/\/lacabanasse.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lacabanasse66210\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DP 0660272500006 - Mairie La Cabanasse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lacabanasse.fr\/es\/documents\/dp-0660272500006\/","og_locale":"es_ES","og_type":"article","og_title":"DP 0660272500006 - Mairie La Cabanasse","og_url":"https:\/\/lacabanasse.fr\/es\/documents\/dp-0660272500006\/","og_site_name":"Mairie La Cabanasse","article_publisher":"https:\/\/www.facebook.com\/lacabanasse66210\/","article_modified_time":"2025-03-21T08:33:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/","url":"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/","name":"DP 0660272500006 - Mairie La Cabanasse","isPartOf":{"@id":"https:\/\/lacabanasse.fr\/#website"},"datePublished":"2025-03-21T08:33:50+00:00","dateModified":"2025-03-21T08:33:51+00:00","breadcrumb":{"@id":"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lacabanasse.fr\/documents\/dp-0660272500006\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lacabanasse.fr\/"},{"@type":"ListItem","position":2,"name":"Documents","item":"https:\/\/lacabanasse.fr\/es\/documents\/"},{"@type":"ListItem","position":3,"name":"DP 0660272500006"}]},{"@type":"WebSite","@id":"https:\/\/lacabanasse.fr\/#website","url":"https:\/\/lacabanasse.fr\/","name":"Ayuntamiento de Cabanasse","description":"Sitio web oficial del Ayuntamiento de La Cabanasse en los Pirineos Orientales","publisher":{"@id":"https:\/\/lacabanasse.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lacabanasse.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/lacabanasse.fr\/#organization","name":"Ayuntamiento de Cabanasse","url":"https:\/\/lacabanasse.fr\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/lacabanasse.fr\/#\/schema\/logo\/image\/","url":"https:\/\/lacabanasse.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-la-cabanasse.jpg","contentUrl":"https:\/\/lacabanasse.fr\/wp-content\/uploads\/2021\/03\/cropped-favicon-la-cabanasse.jpg","width":512,"height":512,"caption":"Mairie de la Cabanasse"},"image":{"@id":"https:\/\/lacabanasse.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lacabanasse66210\/"]}]}},"uagb_featured_image_src":[],"uagb_author_info":{"display_name":"C\u00e9line Plana","author_link":"https:\/\/lacabanasse.fr\/es\/author\/celine-p\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/lsvr_document\/5019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/lsvr_document"}],"about":[{"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/types\/lsvr_document"}],"author":[{"embeddable":true,"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":2,"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/lsvr_document\/5019\/revisions"}],"predecessor-version":[{"id":5022,"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/lsvr_document\/5019\/revisions\/5022"}],"wp:attachment":[{"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/media?parent=5019"}],"wp:term":[{"taxonomy":"lsvr_document_cat","embeddable":true,"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/lsvr_document_cat?post=5019"},{"taxonomy":"lsvr_document_tag","embeddable":true,"href":"https:\/\/lacabanasse.fr\/es\/wp-json\/wp\/v2\/lsvr_document_tag?post=5019"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}